{"id":8884,"date":"2026-05-05T15:59:36","date_gmt":"2026-05-05T12:59:36","guid":{"rendered":"https:\/\/cs.engaz.media\/dubai\/?post_type=product&#038;p=8884"},"modified":"2026-06-16T17:04:33","modified_gmt":"2026-06-16T14:04:33","slug":"%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2","status":"publish","type":"product","link":"https:\/\/dubaiforshopping.com\/en\/product\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\/","title":{"rendered":"\u0637\u0642\u0645 \u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 \u0645\u0633\u0637\u062d \u063a\u0627\u0632 90 \u0633\u0645 5 \u0634\u0639\u0644\u0629 \u062d\u0648\u0627\u0645\u0644 \u0632\u0647\u0631 \u062a\u062d\u0643\u0645 \u0627\u0645\u0627\u0645\u064a \u0627\u0633\u062a\u0627\u0646\u0644\u0633 \u062a\u0635\u0645\u064a\u0645 \u0641\u0644\u0627\u062a \u062c\u062f\u064a\u062f \u0627\u0645\u0627\u0646 \u0643\u0627\u0645\u0644 S903C+G9504T+H96TB"},"content":{"rendered":"<p><span style=\"color: #ff0000;\"><strong>H96TB \u0634\u0641\u0627\u0637 \u0625\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 90\u0633\u0645 \u062d\u0631\u0641T<\/strong><\/span><\/p>\n<p><strong>\u0634\u0641\u0627\u0637 \u0625\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 90 \u0633\u0645 \u0625\u0633\u062a\u0627\u0646\u0644\u0633 \u0633\u062a\u064a\u0644 \u0639\u0644\u0649 \u0634\u0643\u0644 \u062d\u0631\u0641 T \u2013 3 \u0633\u0631\u0639\u0627\u062a\u00d7\u0642\u0648\u0629 650\u0645\u00b3\/\u0627\u0644\u0633\u0627\u0639\u0629 \u2013 \u0641\u0644\u0627\u062a\u0631 \u0645\u0639\u062f\u0646\u064a\u0629 \u0633\u0647\u0644\u0629 \u0627\u0644\u062a\u0646\u0638\u064a\u0641 \u2013 \u0625\u0636\u0627\u0621\u0647 LED \u2013 \u0641\u0644\u0627\u062a\u0631 \u0643\u0631\u0628\u0648\u0646 \u2013 \u0625\u0645\u0643\u0627\u0646\u064a\u0629 \u0627\u0644\u062a\u0634\u063a\u064a\u0644 \u0628\u0627\u0644\u0637\u0631\u062f \u0627\u0644\u062f\u0627\u062e\u0644\u064a (\u0641\u0644\u0627\u062a\u0631 \u0643\u0631\u0628\u0648\u0646) \u0623\u0648 \u0628\u0627\u0644\u0637\u0631\u062f \u0627\u0644\u062e\u0627\u0631\u062c\u064a (\u0645\u062f\u062e\u0646\u0629).<\/strong><\/p>\n<hr \/>\n<p><strong><span style=\"color: #ff0000;\"> G9504T \u0641\u0631\u0646 \u0625\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 90 \u0633\u0645 \u063a\u0627\u0632<\/span> <\/strong><\/p>\n<p><strong>\u0641\u0631\u0646 \u0625\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 90 \u0633\u0645 \u063a\u0627\u0632 \u0634\u0648\u0627\u064a\u0647 \u063a\u0627\u0632 \u0625\u0633\u062a\u0627\u0646\u0644\u0633 \u0628\u0627\u0644\u0645\u0631\u0648\u062d\u0629 \u2013 \u062e\u0627\u0635\u064a\u0629 DEFROST \u0644\u0641\u0643 \u0627\u0644\u062a\u062c\u0645\u064a\u062f \u2013 \u062a\u0627\u064a\u0645\u0631 \u0625\u063a\u0644\u0627\u0642 \u0627\u062a\u0648\u0645\u0627\u062a\u064a\u0643 \u2013 \u0627\u0644\u0634\u0648\u0627\u064a\u0647 \u062a\u0639\u0645\u0644 \u0648 \u0627\u0644\u0628\u0627\u0628 \u0645\u063a\u0644\u0642 \u2013 \u0625\u0634\u0639\u0627\u0644 \u0627\u0648\u062a\u0648\u0645\u0627\u062a\u064a\u0643 \u0644\u0644\u0641\u0631\u0646 \u0648 \u0627\u0644\u0634\u0648\u0627\u064a\u0647 \u2013 \u0623\u0645\u0627\u0646 \u0643\u0627\u0645\u0644 \u0625\u064a\u0637\u0627\u0644\u0649 \u2013 \u0633\u064a\u062e \u0634\u0648\u064a \u0639\u0631\u064a\u0636 \u2013 \u0645\u0631\u0648\u062d\u0629 \u062a\u0628\u0631\u064a\u062f \u062d\u0631\u0627\u0631\u0649 \u2013 \u0645\u0631\u0648\u062d\u0629 \u062a\u0648\u0632\u064a\u0639 \u0627\u0644\u062d\u0631\u0627\u0631\u0629 \u0628\u0646\u0638\u0627\u0645 \u0627\u0644\u0643\u0648\u0646\u0641\u0643\u0634\u0646 &#8211; \u0623\u0643\u0628\u0631 \u0633\u0639\u0647 \u0644\u062a\u0631\u064a\u0647 \u0641\u0649 \u0645\u0635\u0631 105 \u0644\u062a\u0631 XXL \u2013 \u062a\u062c\u0648\u064a\u0641 \u0645\u0633\u0637\u062d \u0644\u0644\u0641\u0631\u0646 \u0633\u0647\u0644 \u0627\u0644\u062a\u0646\u0638\u064a\u0641 \u0645\u0639 \u062d\u0648\u0627\u0645\u0644 \u062c\u0627\u0646\u0628\u064a\u0647 5 \u0645\u0633\u062a\u0648\u064a\u0627\u062a \u0644\u0644\u0635\u064a\u0646\u064a\u0647 \u0648 \u0627\u0644\u0634\u0628\u0643\u0647 \u2013 1 \u0634\u0628\u0643\u0629 + 2 \u0635\u064a\u0646\u064a\u0629 \u0639\u0645\u064a\u0642\u0647 \u2013 \u0632\u062c\u0627\u062c \u0628\u0627\u0628 \u0627\u0644\u0641\u0631\u0646 \u0633\u0647\u0644 \u0627\u0644\u062a\u0646\u0638\u064a\u0641 \u2013 2 \u0644\u0645\u0628\u0629 \u0673\u0636\u0627\u0621\u0647 \u062f\u0627\u062e\u0644\u064a\u0647 \u2013 \u0645\u0648\u0641\u0631 \u0644\u0627\u0633\u062a\u0647\u0644\u0627\u0643 \u0627\u0644\u0637\u0627\u0642\u0647 CLASS A.<\/strong><\/p>\n<hr \/>\n<p class=\"product_title entry-title wd-entities-title\"><span style=\"color: #ff0000;\"><strong>S903C<\/strong> <strong>\u0645\u0633\u0637\u062d \u0625\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 \u063a\u0627\u0632 90 \u0633\u0645 <\/strong><\/span><\/p>\n<p><strong>\u0645\u0633\u0637\u062d \u0625\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 \u063a\u0627\u0632 90 \u0633\u0645 5 \u0634\u0639\u0644\u0629 \u0625\u0633\u062a\u0627\u0646\u0644\u0633 \u0633\u062a\u064a\u0644 \u2013 \u0625\u0634\u0639\u0627\u0644 \u0627\u0648\u062a\u0648\u0645\u0627\u062a\u064a\u0643 \u2013 \u0634\u0639\u0644\u0629 \u062b\u0644\u0627\u062b\u064a\u0629 \u0643\u0628\u064a\u0631\u0629 SABAF \u0625\u064a\u0637\u0627\u0644\u0649 \u2013 3.8Kw \u0623\u0645\u0627\u0646 \u0643\u0627\u0645\u0644 \u0625\u064a\u0637\u0627\u0644\u0649 \u2013 \u062d\u0648\u0627\u0645\u0644 \u0632\u0647\u0631.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>H96TB \u0634\u0641\u0627\u0637 \u0625\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 90\u0633\u0645 \u062d\u0631\u0641T \u0634\u0641\u0627\u0637 \u0625\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 90 \u0633\u0645 \u0625\u0633\u062a\u0627\u0646\u0644\u0633 \u0633\u062a\u064a\u0644 \u0639\u0644\u0649 \u0634\u0643\u0644 \u062d\u0631\u0641 T \u2013 3 \u0633\u0631\u0639\u0627\u062a\u00d7\u0642\u0648\u0629 650\u0645\u00b3\/\u0627\u0644\u0633\u0627\u0639\u0629 \u2013<\/p>\n","protected":false},"featured_media":8920,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[655],"product_cat":[1648,1646,1558,1526,1560,1520,1519,1521,1522,1561,1525,1529,1559],"product_tag":[],"class_list":["post-8884","product","type-product","status-publish","has-post-thumbnail","product_brand-655","product_cat-1648","product_cat-1646","product_cat-1558","product_cat-1526","product_cat-1560","product_cat-1520","product_cat-1519","product_cat-1521","product_cat-1522","product_cat--90-90--","product_cat-1525","product_cat-1529","product_cat-1559","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0637\u0642\u0645 \u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 \u0645\u0633\u0637\u062d \u063a\u0627\u0632 90 \u0633\u0645 5 \u0634\u0639\u0644\u0629 \u062d\u0648\u0627\u0645\u0644 \u0632\u0647\u0631 \u062a\u062d\u0643\u0645 \u0627\u0645\u0627\u0645\u064a \u0627\u0633\u062a\u0627\u0646\u0644\u0633 \u062a\u0635\u0645\u064a\u0645 \u0641\u0644\u0627\u062a \u062c\u062f\u064a\u062f \u0627\u0645\u0627\u0646 \u0643\u0627\u0645\u0644 S903C+G9504T+H96TB | Dubai For Shopping<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dubaiforshopping.com\/\u0645\u0646\u062a\u062c\/\u0637\u0642\u0645-\u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643-\u0645\u0633\u0637\u062d-\u063a\u0627\u0632-90-\u0633\u0645-5-\u0634\u0639\u0644\u0629-\u062d\u0648\u0627\u0645\u0644-\u0632-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0637\u0642\u0645 \u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 \u0645\u0633\u0637\u062d \u063a\u0627\u0632 90 \u0633\u0645 5 \u0634\u0639\u0644\u0629 \u062d\u0648\u0627\u0645\u0644 \u0632\u0647\u0631 \u062a\u062d\u0643\u0645 \u0627\u0645\u0627\u0645\u064a \u0627\u0633\u062a\u0627\u0646\u0644\u0633 \u062a\u0635\u0645\u064a\u0645 \u0641\u0644\u0627\u062a \u062c\u062f\u064a\u062f \u0627\u0645\u0627\u0646 \u0643\u0627\u0645\u0644 S903C+G9504T+H96TB\" \/>\n<meta property=\"og:description\" content=\"H96TB \u0634\u0641\u0627\u0637 \u0625\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 90\u0633\u0645 \u062d\u0631\u0641T \u0634\u0641\u0627\u0637 \u0625\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 90 \u0633\u0645 \u0625\u0633\u062a\u0627\u0646\u0644\u0633 \u0633\u062a\u064a\u0644 \u0639\u0644\u0649 \u0634\u0643\u0644 \u062d\u0631\u0641 T \u2013 3 \u0633\u0631\u0639\u0627\u062a\u00d7\u0642\u0648\u0629 650\u0645\u00b3\/\u0627\u0644\u0633\u0627\u0639\u0629 \u2013\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dubaiforshopping.com\/\u0645\u0646\u062a\u062c\/\u0637\u0642\u0645-\u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643-\u0645\u0633\u0637\u062d-\u063a\u0627\u0632-90-\u0633\u0645-5-\u0634\u0639\u0644\u0629-\u062d\u0648\u0627\u0645\u0644-\u0632-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Dubai For Shopping\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Dubiaforshoppingg\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-16T14:04:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dubaiforshopping.com\/wp-content\/uploads\/2026\/05\/90-5-s903c.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dubaiforshopping.com\\\/\u0645\u0646\u062a\u062c\\\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\\\/\",\"url\":\"https:\\\/\\\/dubaiforshopping.com\\\/\u0645\u0646\u062a\u062c\\\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\\\/\",\"name\":\"\u0637\u0642\u0645 \u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 \u0645\u0633\u0637\u062d \u063a\u0627\u0632 90 \u0633\u0645 5 \u0634\u0639\u0644\u0629 \u062d\u0648\u0627\u0645\u0644 \u0632\u0647\u0631 \u062a\u062d\u0643\u0645 \u0627\u0645\u0627\u0645\u064a \u0627\u0633\u062a\u0627\u0646\u0644\u0633 \u062a\u0635\u0645\u064a\u0645 \u0641\u0644\u0627\u062a \u062c\u062f\u064a\u062f \u0627\u0645\u0627\u0646 \u0643\u0627\u0645\u0644 S903C+G9504T+H96TB | Dubai For Shopping\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dubaiforshopping.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dubaiforshopping.com\\\/\u0645\u0646\u062a\u062c\\\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dubaiforshopping.com\\\/\u0645\u0646\u062a\u062c\\\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/dubaiforshopping.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/90-5-s903c.webp?fit=500%2C500&ssl=1\",\"datePublished\":\"2026-05-05T12:59:36+00:00\",\"dateModified\":\"2026-06-16T14:04:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dubaiforshopping.com\\\/\u0645\u0646\u062a\u062c\\\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dubaiforshopping.com\\\/\u0645\u0646\u062a\u062c\\\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dubaiforshopping.com\\\/\u0645\u0646\u062a\u062c\\\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/dubaiforshopping.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/90-5-s903c.webp?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/dubaiforshopping.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/90-5-s903c.webp?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dubaiforshopping.com\\\/\u0645\u0646\u062a\u062c\\\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dubaiforshopping.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/dubaiforshopping.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0637\u0642\u0645 \u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 \u0645\u0633\u0637\u062d \u063a\u0627\u0632 90 \u0633\u0645 5 \u0634\u0639\u0644\u0629 \u062d\u0648\u0627\u0645\u0644 \u0632\u0647\u0631 \u062a\u062d\u0643\u0645 \u0627\u0645\u0627\u0645\u064a \u0627\u0633\u062a\u0627\u0646\u0644\u0633 \u062a\u0635\u0645\u064a\u0645 \u0641\u0644\u0627\u062a \u062c\u062f\u064a\u062f \u0627\u0645\u0627\u0646 \u0643\u0627\u0645\u0644 S903C+G9504T+H96TB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dubaiforshopping.com\\\/#website\",\"url\":\"https:\\\/\\\/dubaiforshopping.com\\\/\",\"name\":\"\u062f\u0628\u064a \u0644\u0644\u062a\u0633\u0648\u0642\",\"description\":\"Smart devices for elegant homes\",\"publisher\":{\"@id\":\"https:\\\/\\\/dubaiforshopping.com\\\/#organization\"},\"alternateName\":\"Dubai For Shopping\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dubaiforshopping.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dubaiforshopping.com\\\/#organization\",\"name\":\"\u062f\u0628\u064a \u0644\u0644\u062a\u0633\u0648\u0642\",\"url\":\"https:\\\/\\\/dubaiforshopping.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dubaiforshopping.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/dubaiforshopping.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dubai-for-shopping-logo.png?fit=407%2C130&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/dubaiforshopping.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/dubai-for-shopping-logo.png?fit=407%2C130&ssl=1\",\"width\":407,\"height\":130,\"caption\":\"\u062f\u0628\u064a \u0644\u0644\u062a\u0633\u0648\u0642\"},\"image\":{\"@id\":\"https:\\\/\\\/dubaiforshopping.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Dubiaforshoppingg\",\"https:\\\/\\\/www.instagram.com\\\/dubaiforshopping.egypt\",\"https:\\\/\\\/www.tiktok.com\\\/@dubaiforshopping\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0637\u0642\u0645 \u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 \u0645\u0633\u0637\u062d \u063a\u0627\u0632 90 \u0633\u0645 5 \u0634\u0639\u0644\u0629 \u062d\u0648\u0627\u0645\u0644 \u0632\u0647\u0631 \u062a\u062d\u0643\u0645 \u0627\u0645\u0627\u0645\u064a \u0627\u0633\u062a\u0627\u0646\u0644\u0633 \u062a\u0635\u0645\u064a\u0645 \u0641\u0644\u0627\u062a \u062c\u062f\u064a\u062f \u0627\u0645\u0627\u0646 \u0643\u0627\u0645\u0644 S903C+G9504T+H96TB | Dubai For Shopping","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dubaiforshopping.com\/\u0645\u0646\u062a\u062c\/\u0637\u0642\u0645-\u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643-\u0645\u0633\u0637\u062d-\u063a\u0627\u0632-90-\u0633\u0645-5-\u0634\u0639\u0644\u0629-\u062d\u0648\u0627\u0645\u0644-\u0632-2\/","og_locale":"en_US","og_type":"article","og_title":"\u0637\u0642\u0645 \u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 \u0645\u0633\u0637\u062d \u063a\u0627\u0632 90 \u0633\u0645 5 \u0634\u0639\u0644\u0629 \u062d\u0648\u0627\u0645\u0644 \u0632\u0647\u0631 \u062a\u062d\u0643\u0645 \u0627\u0645\u0627\u0645\u064a \u0627\u0633\u062a\u0627\u0646\u0644\u0633 \u062a\u0635\u0645\u064a\u0645 \u0641\u0644\u0627\u062a \u062c\u062f\u064a\u062f \u0627\u0645\u0627\u0646 \u0643\u0627\u0645\u0644 S903C+G9504T+H96TB","og_description":"H96TB \u0634\u0641\u0627\u0637 \u0625\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 90\u0633\u0645 \u062d\u0631\u0641T \u0634\u0641\u0627\u0637 \u0625\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 90 \u0633\u0645 \u0625\u0633\u062a\u0627\u0646\u0644\u0633 \u0633\u062a\u064a\u0644 \u0639\u0644\u0649 \u0634\u0643\u0644 \u062d\u0631\u0641 T \u2013 3 \u0633\u0631\u0639\u0627\u062a\u00d7\u0642\u0648\u0629 650\u0645\u00b3\/\u0627\u0644\u0633\u0627\u0639\u0629 \u2013","og_url":"https:\/\/dubaiforshopping.com\/\u0645\u0646\u062a\u062c\/\u0637\u0642\u0645-\u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643-\u0645\u0633\u0637\u062d-\u063a\u0627\u0632-90-\u0633\u0645-5-\u0634\u0639\u0644\u0629-\u062d\u0648\u0627\u0645\u0644-\u0632-2\/","og_site_name":"Dubai For Shopping","article_publisher":"https:\/\/www.facebook.com\/Dubiaforshoppingg","article_modified_time":"2026-06-16T14:04:33+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/dubaiforshopping.com\/wp-content\/uploads\/2026\/05\/90-5-s903c.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dubaiforshopping.com\/\u0645\u0646\u062a\u062c\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\/","url":"https:\/\/dubaiforshopping.com\/\u0645\u0646\u062a\u062c\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\/","name":"\u0637\u0642\u0645 \u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 \u0645\u0633\u0637\u062d \u063a\u0627\u0632 90 \u0633\u0645 5 \u0634\u0639\u0644\u0629 \u062d\u0648\u0627\u0645\u0644 \u0632\u0647\u0631 \u062a\u062d\u0643\u0645 \u0627\u0645\u0627\u0645\u064a \u0627\u0633\u062a\u0627\u0646\u0644\u0633 \u062a\u0635\u0645\u064a\u0645 \u0641\u0644\u0627\u062a \u062c\u062f\u064a\u062f \u0627\u0645\u0627\u0646 \u0643\u0627\u0645\u0644 S903C+G9504T+H96TB | Dubai For Shopping","isPartOf":{"@id":"https:\/\/dubaiforshopping.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dubaiforshopping.com\/\u0645\u0646\u062a\u062c\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\/#primaryimage"},"image":{"@id":"https:\/\/dubaiforshopping.com\/\u0645\u0646\u062a\u062c\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/dubaiforshopping.com\/wp-content\/uploads\/2026\/05\/90-5-s903c.webp?fit=500%2C500&ssl=1","datePublished":"2026-05-05T12:59:36+00:00","dateModified":"2026-06-16T14:04:33+00:00","breadcrumb":{"@id":"https:\/\/dubaiforshopping.com\/\u0645\u0646\u062a\u062c\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dubaiforshopping.com\/\u0645\u0646\u062a\u062c\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dubaiforshopping.com\/\u0645\u0646\u062a\u062c\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\/#primaryimage","url":"https:\/\/i0.wp.com\/dubaiforshopping.com\/wp-content\/uploads\/2026\/05\/90-5-s903c.webp?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/dubaiforshopping.com\/wp-content\/uploads\/2026\/05\/90-5-s903c.webp?fit=500%2C500&ssl=1","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/dubaiforshopping.com\/\u0645\u0646\u062a\u062c\/%d8%b7%d9%82%d9%85-%d8%a7%d9%8a%d9%83%d9%88%d9%85%d8%a7%d8%aa%d9%8a%d9%83-%d9%85%d8%b3%d8%b7%d8%ad-%d8%ba%d8%a7%d8%b2-90-%d8%b3%d9%85-5-%d8%b4%d8%b9%d9%84%d8%a9-%d8%ad%d9%88%d8%a7%d9%85%d9%84-%d8%b2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dubaiforshopping.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/dubaiforshopping.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"\u0637\u0642\u0645 \u0627\u064a\u0643\u0648\u0645\u0627\u062a\u064a\u0643 \u0645\u0633\u0637\u062d \u063a\u0627\u0632 90 \u0633\u0645 5 \u0634\u0639\u0644\u0629 \u062d\u0648\u0627\u0645\u0644 \u0632\u0647\u0631 \u062a\u062d\u0643\u0645 \u0627\u0645\u0627\u0645\u064a \u0627\u0633\u062a\u0627\u0646\u0644\u0633 \u062a\u0635\u0645\u064a\u0645 \u0641\u0644\u0627\u062a \u062c\u062f\u064a\u062f \u0627\u0645\u0627\u0646 \u0643\u0627\u0645\u0644 S903C+G9504T+H96TB"}]},{"@type":"WebSite","@id":"https:\/\/dubaiforshopping.com\/#website","url":"https:\/\/dubaiforshopping.com\/","name":"\u062f\u0628\u064a \u0644\u0644\u062a\u0633\u0648\u0642","description":"Smart devices for elegant homes","publisher":{"@id":"https:\/\/dubaiforshopping.com\/#organization"},"alternateName":"Dubai For Shopping","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dubaiforshopping.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dubaiforshopping.com\/#organization","name":"\u062f\u0628\u064a \u0644\u0644\u062a\u0633\u0648\u0642","url":"https:\/\/dubaiforshopping.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dubaiforshopping.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/dubaiforshopping.com\/wp-content\/uploads\/2026\/05\/dubai-for-shopping-logo.png?fit=407%2C130&ssl=1","contentUrl":"https:\/\/i0.wp.com\/dubaiforshopping.com\/wp-content\/uploads\/2026\/05\/dubai-for-shopping-logo.png?fit=407%2C130&ssl=1","width":407,"height":130,"caption":"\u062f\u0628\u064a \u0644\u0644\u062a\u0633\u0648\u0642"},"image":{"@id":"https:\/\/dubaiforshopping.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Dubiaforshoppingg","https:\/\/www.instagram.com\/dubaiforshopping.egypt","https:\/\/www.tiktok.com\/@dubaiforshopping"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/dubaiforshopping.com\/en\/wp-json\/wp\/v2\/product\/8884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dubaiforshopping.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dubaiforshopping.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dubaiforshopping.com\/en\/wp-json\/wp\/v2\/comments?post=8884"}],"version-history":[{"count":3,"href":"https:\/\/dubaiforshopping.com\/en\/wp-json\/wp\/v2\/product\/8884\/revisions"}],"predecessor-version":[{"id":12927,"href":"https:\/\/dubaiforshopping.com\/en\/wp-json\/wp\/v2\/product\/8884\/revisions\/12927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dubaiforshopping.com\/en\/wp-json\/wp\/v2\/media\/8920"}],"wp:attachment":[{"href":"https:\/\/dubaiforshopping.com\/en\/wp-json\/wp\/v2\/media?parent=8884"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dubaiforshopping.com\/en\/wp-json\/wp\/v2\/product_brand?post=8884"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dubaiforshopping.com\/en\/wp-json\/wp\/v2\/product_cat?post=8884"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dubaiforshopping.com\/en\/wp-json\/wp\/v2\/product_tag?post=8884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}